{"id":41328,"date":"2023-05-17T12:30:53","date_gmt":"2023-05-17T09:30:53","guid":{"rendered":"https:\/\/elai.io\/brand-kit"},"modified":"2025-05-16T20:15:41","modified_gmt":"2025-05-16T17:15:41","slug":"brand-kit","status":"publish","type":"page","link":"https:\/\/elai.io\/pt-pt\/brand-kit\/","title":{"rendered":"Brand kit"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"41328\" class=\"elementor elementor-41328 elementor-34363\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c45f58b elementor-section-height-full box-media-library scaleble-bg elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"5c45f58b\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-693575e4\" data-id=\"693575e4\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c7359c elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-spacer\" data-id=\"8c7359c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e4383e6 title elementor-widget elementor-widget-text-editor\" data-id=\"3e4383e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1 class=\"box-first-text1\" style=\"max-width: 900px;\">Cria\u00e7\u00e3o de v\u00eddeos IA usando o kit da sua marca<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f9ba506 elementor-widget elementor-widget-text-editor\" data-id=\"5f9ba506\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"box-first-text2\" style=\"max-width: 650px;\">Personalize seus v\u00eddeos alinhando-os \u00e0 identidade visual da sua marca, adicionando logotipos e cores para uma experi\u00eancia visual consistente.<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1ab391 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ab391\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5d45de26\" data-id=\"5d45de26\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15ef7950 elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"15ef7950\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/app.elai.io\/signup\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Experimente Elai gratuitamente<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-74653c45 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-spacer\" data-id=\"74653c45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1501eb88 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1501eb88\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5e54374f\" data-id=\"5e54374f\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a70776c elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-spacer\" data-id=\"7a70776c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7eaf32ba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7eaf32ba\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ea4011\" data-id=\"6ea4011\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f6c7a1 elementor-hidden-mobile elementor-widget elementor-widget-html\" data-id=\"1f6c7a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"https:\/\/app.elai.io\/signup\" style=\"cursor: pointer;\"><div class=\"box-001-brand-kit\">\r\n<div class=\"box-001-brand-kit-block\">\r\n<\/div>\r\n<div class=\"box-001-brand-kit-text\"><span style=\"color: #4868FF;\">Aprimore a Est\u00e9tica e a Percep\u00e7\u00e3o de Seu V\u00eddeo<\/span> com Elementos da Sua Marca<\/div>\r\n<div class=\"box-001-brand-kit-text2\"><div style=\"padding-bottom: 8px;\"> Ao integrar elementos da sua marca, como logotipo e cores, voc\u00ea pode criar uma identidade visual uniforme para seus v\u00eddeos, garantindo que estejam alinhados \u00e0 apar\u00eancia geral da sua marca.<\/div>\r\n<div>Com o Elai, adicionar esses elementos de marca aos seus v\u00eddeos \u00e9 simples, permitindo a cria\u00e7\u00e3o de conte\u00fado visualmente atraente que contribui para estabelecer a identidade da sua marca na mente dos espectadores.<\/div><\/div>\r\n<div class=\"box-001-brand-kit-button\">Come\u00e7ar <img decoding=\"async\" class=\"alignnone size-full wp-image-10768\"  src=\"\/wp-content\/uploads\/2022\/08\/Arrow-3.svg\"   \/><\/div>\r\n\r\n<\/div><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f3fe277 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-html\" data-id=\"1f3fe277\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"https:\/\/app.elai.io\/signup\" style=\"cursor: pointer;\"><div class=\"box-001-brand-kit\">\r\n<div class=\"box-001-brand-kit-block\">\r\n<\/div>\r\n<div class=\"box-001-brand-kit-text\">Aprimore a Est\u00e9tica e a Percep\u00e7\u00e3o de Seu V\u00eddeo com Elementos da Sua Marca<\/div>\r\n<div class=\"box-001-brand-kit-text2\">By incorporating your brand elements such as logo and colors, you can create a consistent visual identity for your videos that aligns with your brand's overall look and feel.<br><br>\r\nWith Elai, you can add these brand elements to your videos with ease, creating visually compelling content that helps establish your brand's identity in their minds.<\/div>\r\n\r\n\r\n<\/div><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e2aaad1 elementor-align-center elementor-mobile-align-center elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"6e2aaad1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/app.elai.io\/signup\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Come\u00e7ar<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-43269f83 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"43269f83\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5558adcb\" data-id=\"5558adcb\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a5d483a elementor-widget elementor-widget-spacer\" data-id=\"1a5d483a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fecf5ea title elementor-widget elementor-widget-text-editor\" data-id=\"4fecf5ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"box-001-text-title\" style=\"max-width: 640px; margin: auto;\">Raz\u00f5es para Escolher o Elai.io para Cria\u00e7\u00e3o de V\u00eddeos<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43caae2b elementor-widget elementor-widget-spacer\" data-id=\"43caae2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e8682d0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e8682d0\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7f2c74e3\" data-id=\"7f2c74e3\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3870fee8 elementor-widget elementor-widget-html\" data-id=\"3870fee8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"\/how-it-works\" style=\"text-decoration: none;\"><div class=\"box-004-ai-news-generator\">\r\n<div class=\"box-004-block-ai-news-generator\"> \r\n\r\n<div class=\"box-004-ai-news-generator-text1\">Ferramenta F\u00e1cil de Usar<\/div>\r\n<div class=\"box-004-ai-news-generator-text2\">N\u00e3o s\u00e3o necess\u00e1rias habilidades especiais na cria\u00e7\u00e3o de v\u00eddeos. Com o Elai, \u00e9 extremamente simples produzir v\u00eddeos corporativos com um apresentador humano real.\r\n <\/div>\r\n<div class=\"box-003-button-ai-news-generator\">\r\nSaber mais\r\n<div class=\"box-003-arrow\"><\/div>\r\n<\/div><\/div><\/div><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-737377b5\" data-id=\"737377b5\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45806234 elementor-widget elementor-widget-html\" data-id=\"45806234\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"\/elai-languages\" style=\"text-decoration: none;\"><div class=\"box-004-ai-news-generator\">\r\n<div class=\"box-004-block-ai-news-generator\"> \r\n\r\n<div class=\"box-004-ai-news-generator-text1\">Mais de 75 Idiomas<\/div>\r\n<div class=\"box-004-ai-news-generator-text2\">A localiza\u00e7\u00e3o nunca foi t\u00e3o f\u00e1cil! Com suporte para mais de 75 idiomas, voc\u00ea pode alcan\u00e7ar seus funcion\u00e1rios, stakeholders e investidores em todos os cantos do mundo.<\/div>\r\n<div class=\"box-003-button-ai-news-generator\">\r\nSaber mais\r\n<div class=\"box-003-arrow\"><\/div>\r\n<\/div><\/div><\/div><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c48b32e\" data-id=\"c48b32e\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-617c7122 elementor-widget elementor-widget-html\" data-id=\"617c7122\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"\/platform\" style=\"text-decoration: none;\"><div class=\"box-004-ai-news-generator\">\r\n<div class=\"box-004-block-ai-news-generator\"> \r\n\r\n<div class=\"box-004-ai-news-generator-text1\">Ferramenta Eficiente de Tomada de Decis\u00e3o<\/div>\r\n<div class=\"box-004-ai-news-generator-text2\">Reduza o tempo precioso gasto na cria\u00e7\u00e3o de v\u00eddeos com IA. N\u00e3o \u00e9 necess\u00e1rio est\u00fadio ou equipamento especial. Hoje, a cria\u00e7\u00e3o de v\u00eddeos \u00e9 t\u00e3o f\u00e1cil e r\u00e1pida quanto trocar uma l\u00e2mpada. <\/div>\r\n<div class=\"box-003-button-ai-news-generator\">\r\nSaber mais\r\n<div class=\"box-003-arrow\"><\/div>\r\n<\/div><\/div><\/div><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4874477c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4874477c\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b72cf17\" data-id=\"4b72cf17\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e0a98b9 elementor-widget elementor-widget-spacer\" data-id=\"1e0a98b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12c2d676 title elementor-widget elementor-widget-text-editor\" data-id=\"12c2d676\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"box-001-text-title\" style=\"max-width: 800px; margin: auto;\">Utilizando Elementos da Marca na Cria\u00e7\u00e3o de V\u00eddeos: Dicas e Estrat\u00e9gias<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75575909 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"75575909\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f381469\" data-id=\"3f381469\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6ee9a924 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ee9a924\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1edfc7e4\" data-id=\"1edfc7e4\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45ee6a1a elementor-widget elementor-widget-html\" data-id=\"45ee6a1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"box-005-media-library\">\r\n<div class=\"box-005-media-library-block3\">\r\n<div class=\"box-005-media-library-title\">Priorize a Identidade Visual<\/div>\r\n<div class=\"box-005-media-library-text\">Maximize o reconhecimento da marca, dando destaque aos elementos visuais, como a posi\u00e7\u00e3o do logotipo e o esquema de cores.<\/div>\r\n\r\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c3a453b elementor-widget elementor-widget-html\" data-id=\"5c3a453b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"box-005-media-library\">\r\n<div class=\"box-005-media-library-block3\">\r\n<div class=\"box-005-media-library-title\">Mantenha as Coisas Simples<\/div>\r\n<div class=\"box-005-media-library-text\">Evite sobrecarregar seus v\u00eddeos com muitos elementos de marca para n\u00e3o prejudicar a mensagem que voc\u00ea est\u00e1 tentando transmitir.<\/div>\r\n\r\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bae4f36 elementor-widget elementor-widget-html\" data-id=\"2bae4f36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"box-005-media-library\">\r\n<div class=\"box-005-media-library-block3\">\r\n<div class=\"box-005-media-library-title\">Pense no Seu P\u00fablico-Alvo<\/div>\r\n<div class=\"box-005-media-library-text\">A identidade da sua marca deve ressoar com seu p\u00fablico-alvo, construindo uma conex\u00e3o significativa.<\/div>\r\n\r\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3906e3d7\" data-id=\"3906e3d7\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2284d433 elementor-widget elementor-widget-spacer\" data-id=\"2284d433\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1167053e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1167053e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-11457115\" data-id=\"11457115\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-589266ce elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"589266ce\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9a3ecec\" data-id=\"9a3ecec\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e79721d elementor-widget elementor-widget-spacer\" data-id=\"3e79721d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4122b171\" data-id=\"4122b171\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c9b70aa elementor-widget elementor-widget-html\" data-id=\"4c9b70aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"box-005-media-library\">\r\n<div class=\"box-005-media-library-block3\">\r\n<div class=\"box-005-media-library-title\">Seja Consistente<\/div>\r\n<div class=\"box-005-media-library-text\">Garanta que os elementos da sua marca, como cores, tipografia e logotipo, sejam consistentes em todos os materiais de marketing, incluindo v\u00eddeos.<\/div>\r\n\r\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30366678 elementor-widget elementor-widget-html\" data-id=\"30366678\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"box-005-media-library\">\r\n<div class=\"box-005-media-library-block3\">\r\n<div class=\"box-005-media-library-title\">Considere Adicionar Anima\u00e7\u00e3o ou Gr\u00e1ficos em Movimento<\/div>\r\n<div class=\"box-005-media-library-text\">A incorpora\u00e7\u00e3o de anima\u00e7\u00e3o ou gr\u00e1ficos em movimento aos elementos da sua marca pode torn\u00e1-los mais din\u00e2micos e envolventes, capturando a aten\u00e7\u00e3o do espectador.<\/div>\r\n\r\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ced3103 elementor-widget elementor-widget-html\" data-id=\"ced3103\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"box-005-media-library\">\r\n<div class=\"box-005-media-library-block3\">\r\n<div class=\"box-005-media-library-title\">Teste e Refine<\/div>\r\n<div class=\"box-005-media-library-text\">Assim como em qualquer estrat\u00e9gia de marketing, teste e refine o uso dos elementos da marca nos v\u00eddeos ao longo do tempo para garantir sua efic\u00e1cia na consecu\u00e7\u00e3o dos objetivos de marketing.<\/div>\r\n\r\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-7a3e77f4 elementor-widget elementor-widget-spacer\" data-id=\"7a3e77f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d7d506d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d7d506d\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2d9bf591\" data-id=\"2d9bf591\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-542334c3 elementor-widget elementor-widget-spacer\" data-id=\"542334c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Cria\u00e7\u00e3o de v\u00eddeos IA usando o kit da sua marca Personalize seus v\u00eddeos alinhando-os \u00e0 identidade visual da sua marca, adicionando logotipos e cores para uma experi\u00eancia visual consistente. Experimente Elai gratuitamente Aprimore a Est\u00e9tica e a Percep\u00e7\u00e3o de Seu V\u00eddeo com Elementos da Sua Marca Ao integrar elementos da sua marca, como logotipo e [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":41330,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-41328","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kit de marca - Elai.io<\/title>\n<meta name=\"description\" content=\"Alinhe seus v\u00eddeos com a apar\u00eancia geral da sua marca, adicionando logotipos e cores para uma identidade visual consistente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elai.io\/pt-pt\/brand-kit\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brand kit\" \/>\n<meta property=\"og:description\" content=\"Alinhe seus v\u00eddeos com a apar\u00eancia geral da sua marca, adicionando logotipos e cores para uma identidade visual consistente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elai.io\/pt-pt\/brand-kit\/\" \/>\n<meta property=\"og:site_name\" content=\"Elai.io\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-16T17:15:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elai.io\/wp-content\/uploads\/2023\/05\/Rectangle-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1656\" \/>\n\t<meta property=\"og:image:height\" content=\"1324\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elai.io\\\/pt-pt\\\/brand-kit\\\/\",\"url\":\"https:\\\/\\\/elai.io\\\/pt-pt\\\/brand-kit\\\/\",\"name\":\"Kit de marca - Elai.io\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elai.io\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elai.io\\\/pt-pt\\\/brand-kit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elai.io\\\/pt-pt\\\/brand-kit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elai.io\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Rectangle-1.png\",\"datePublished\":\"2023-05-17T09:30:53+00:00\",\"dateModified\":\"2025-05-16T17:15:41+00:00\",\"description\":\"Alinhe seus v\u00eddeos com a apar\u00eancia geral da sua marca, adicionando logotipos e cores para uma identidade visual consistente.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elai.io\\\/pt-pt\\\/brand-kit\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elai.io\\\/pt-pt\\\/brand-kit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/elai.io\\\/pt-pt\\\/brand-kit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elai.io\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Rectangle-1.png\",\"contentUrl\":\"https:\\\/\\\/elai.io\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Rectangle-1.png\",\"width\":1656,\"height\":1324},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elai.io\\\/pt-pt\\\/brand-kit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elai.io\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brand kit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elai.io\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/elai.io\\\/pt-pt\\\/\",\"name\":\"Elai.io\",\"description\":\"create AI videos from text\",\"publisher\":{\"@id\":\"https:\\\/\\\/elai.io\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elai.io\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elai.io\\\/pt-pt\\\/#organization\",\"name\":\"Elai.io\",\"url\":\"https:\\\/\\\/elai.io\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/elai.io\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elai.io\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Component-2.svg\",\"contentUrl\":\"https:\\\/\\\/elai.io\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Component-2.svg\",\"caption\":\"Elai.io\"},\"image\":{\"@id\":\"https:\\\/\\\/elai.io\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kit de marca - Elai.io","description":"Alinhe seus v\u00eddeos com a apar\u00eancia geral da sua marca, adicionando logotipos e cores para uma identidade visual consistente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elai.io\/pt-pt\/brand-kit\/","og_locale":"pt_PT","og_type":"article","og_title":"Brand kit","og_description":"Alinhe seus v\u00eddeos com a apar\u00eancia geral da sua marca, adicionando logotipos e cores para uma identidade visual consistente.","og_url":"https:\/\/elai.io\/pt-pt\/brand-kit\/","og_site_name":"Elai.io","article_modified_time":"2025-05-16T17:15:41+00:00","og_image":[{"width":1656,"height":1324,"url":"https:\/\/elai.io\/wp-content\/uploads\/2023\/05\/Rectangle-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elai.io\/pt-pt\/brand-kit\/","url":"https:\/\/elai.io\/pt-pt\/brand-kit\/","name":"Kit de marca - Elai.io","isPartOf":{"@id":"https:\/\/elai.io\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elai.io\/pt-pt\/brand-kit\/#primaryimage"},"image":{"@id":"https:\/\/elai.io\/pt-pt\/brand-kit\/#primaryimage"},"thumbnailUrl":"https:\/\/elai.io\/wp-content\/uploads\/2023\/05\/Rectangle-1.png","datePublished":"2023-05-17T09:30:53+00:00","dateModified":"2025-05-16T17:15:41+00:00","description":"Alinhe seus v\u00eddeos com a apar\u00eancia geral da sua marca, adicionando logotipos e cores para uma identidade visual consistente.","breadcrumb":{"@id":"https:\/\/elai.io\/pt-pt\/brand-kit\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elai.io\/pt-pt\/brand-kit\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/elai.io\/pt-pt\/brand-kit\/#primaryimage","url":"https:\/\/elai.io\/wp-content\/uploads\/2023\/05\/Rectangle-1.png","contentUrl":"https:\/\/elai.io\/wp-content\/uploads\/2023\/05\/Rectangle-1.png","width":1656,"height":1324},{"@type":"BreadcrumbList","@id":"https:\/\/elai.io\/pt-pt\/brand-kit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elai.io\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Brand kit"}]},{"@type":"WebSite","@id":"https:\/\/elai.io\/pt-pt\/#website","url":"https:\/\/elai.io\/pt-pt\/","name":"Elai.io","description":"create AI videos from text","publisher":{"@id":"https:\/\/elai.io\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elai.io\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/elai.io\/pt-pt\/#organization","name":"Elai.io","url":"https:\/\/elai.io\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/elai.io\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/elai.io\/wp-content\/uploads\/2024\/10\/Component-2.svg","contentUrl":"https:\/\/elai.io\/wp-content\/uploads\/2024\/10\/Component-2.svg","caption":"Elai.io"},"image":{"@id":"https:\/\/elai.io\/pt-pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/elai.io\/pt-pt\/wp-json\/wp\/v2\/pages\/41328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elai.io\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/elai.io\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/elai.io\/pt-pt\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/elai.io\/pt-pt\/wp-json\/wp\/v2\/comments?post=41328"}],"version-history":[{"count":0,"href":"https:\/\/elai.io\/pt-pt\/wp-json\/wp\/v2\/pages\/41328\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elai.io\/pt-pt\/wp-json\/wp\/v2\/media\/41330"}],"wp:attachment":[{"href":"https:\/\/elai.io\/pt-pt\/wp-json\/wp\/v2\/media?parent=41328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}